{"id":3184,"date":"2022-07-05T14:35:21","date_gmt":"2022-07-05T14:35:21","guid":{"rendered":"http:\/\/ffbenefits.ffga.com\/allenisd\/?page_id=3184"},"modified":"2022-07-05T17:20:50","modified_gmt":"2022-07-05T17:20:50","slug":"clever-rx-2022","status":"publish","type":"page","link":"https:\/\/ffbenefits.ffga.com\/allenisd\/clever-rx-2022\/","title":{"rendered":"Clever RX &#8211; 2022"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gulk3-4541ccd0af1190caf4566779643ac949\">\n.flex_column.av-gulk3-4541ccd0af1190caf4566779643ac949{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gulk3-4541ccd0af1190caf4566779643ac949 av_one_full  avia-builder-el-0  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jv8tbj57-51875317e04183b1c7f16e610b66dd84\">\n.avia-image-container.av-jv8tbj57-51875317e04183b1c7f16e610b66dd84 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-jv8tbj57-51875317e04183b1c7f16e610b66dd84 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-jv8tbj57-51875317e04183b1c7f16e610b66dd84 av-styling- avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2492 avia-img-lazy-loading-not-2492 avia_image ' src=\"\/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRX-1030x139-1030x139-1030x139.png\" alt='' title='CleverRX-1030x139-1030x139'  height=\"139\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"\/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRX-1030x139-1030x139.png 1030w, \/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRX-1030x139-1030x139-300x40.png 300w, \/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRX-1030x139-1030x139-768x104.png 768w, \/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRX-1030x139-1030x139-705x95.png 705w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-20zxnlv-c6eeb879caba4b1318d03782c40f4bb2\">\n.flex_column.av-20zxnlv-c6eeb879caba4b1318d03782c40f4bb2{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-20zxnlv-c6eeb879caba4b1318d03782c40f4bb2 av_three_fifth  avia-builder-el-2  el_after_av_one_full  el_before_av_two_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-1zz4f9v-5cd6211c037f7a2963633cc5b356b014 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p><strong>What is Clever RX?<\/strong><\/p>\n<p>Clever RX helps you save money by using a prescription drug savings card. They partner with the healthcare community to bring state-of-the-art, money-savings tools to participants. It helps you save up to 80% off prescriptions drugs and often beats the average copay. Plus, it\u2019s completely free. Thanks to Clever RX, you will never overpay for prescriptions again!<\/p>\n<p><strong>Highlights<\/strong><\/p>\n<ul>\n<li>100% FREE to use.<\/li>\n<li>Unlock discounts on thousands of medications.<\/li>\n<li>Save up to 80% on prescription medication \u2013 Often beats your copay!<\/li>\n<li>Download the Clever RX app by using the information on your card below to unlock exclusive savings at over 60,000 pharmacies nationwide.<\/li>\n<li>Available to use now!<\/li>\n<\/ul>\n<p>Use Clever RX every time you pay for a medication for instant savings! Download the app or visit the site to price a drug: <a href=\"https:\/\/urldefense.proofpoint.com\/v2\/url?u=https-3A__partner.cleverrx.com_ffga&#038;d=DwMF-g&#038;c=dhDJc4qz1nBg1X_FlQsBYTA5Bs4LlEh70jOebecaCck&#038;r=haMIoZb0rUzP17E78XZiGhz2TlDx1jiA9xHWL026S_U&#038;m=k9KZEDkRi7OqGCls7yUt_vwkyUw5-rj2LzOWacDIrUM&#038;s=4iYZkGNCBLyRNq9O34HbdM0dvfP1L1-1EaR0zVdbqOM&#038;e=\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/partner.cleverrx.com\/ffga.\u00a0<\/a><\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-xyc0nn-02fad61407377010b988d9f074dc2cb4\">\n.flex_column.av-xyc0nn-02fad61407377010b988d9f074dc2cb4{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-xyc0nn-02fad61407377010b988d9f074dc2cb4 av_two_fifth  avia-builder-el-4  el_after_av_three_fifth  el_before_av_one_full  flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-wp5n9v-46ab6066d389c1ca3e16a0c2b63eec53\">\n.iconbox.av-wp5n9v-46ab6066d389c1ca3e16a0c2b63eec53 .iconbox_icon{\nbackground-color:#c42032;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-wp5n9v-46ab6066d389c1ca3e16a0c2b63eec53  avia-builder-el-5  el_before_av_iconlist  avia-builder-el-first  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: Clever RX\"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='' data-av_iconfont='entypo-fontello' title=\"Clever RX\" desc=\"Clever RX\" ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/partner.cleverrx.com\/ffga' title='Clever RX'  target=\"_blank\"  rel=\"noopener noreferrer\" >Clever RX<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p>BIN: 610378<\/p>\n<p>PCN: SC1<\/p>\n<p>Group: 1062<\/p>\n<p>Member ID: 1000<\/p>\n<p>Pharmacist Help Line: (800) 974-3135<\/p>\n<p>Customer Help Line: (800) 873-1195<\/p>\n<p><a href=\"https:\/\/partner.cleverrx.com\/ffga\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/partner.cleverrx.com\/ffga<\/a><\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803\">\n#top .avia-icon-list-container.av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 .iconlist_icon{\ncolor:#ffffff;\nbackground-color:#c42032;\n}\n#top .avia-icon-list-container.av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 .iconlist_icon svg:first-child{\nstroke:#ffffff;\nfill:#ffffff;\n}\n<\/style>\n<div  class='avia-icon-list-container av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803  avia-builder-el-6  el_after_av_icon_box  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-28jkuh-7d820ac901ed2097954092b0ec3a1915 avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue81f' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: CLEVER RX PLAN INFORMATION\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >CLEVER RX PLAN INFORMATION<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p><a href=\"\/wp-content\/uploads\/sites\/1667\/2019\/10\/Clever-RX-FFGA-online-flyer1-2.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Clever RX Online Flyer<\/a><\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-25xhah-c67eb91c4b488429a1aada8062313925\">\n.flex_column.av-25xhah-c67eb91c4b488429a1aada8062313925{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-25xhah-c67eb91c4b488429a1aada8062313925 av_one_full  avia-builder-el-7  el_after_av_two_fifth  el_before_av_hr  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1sb813u-a682d41e5e0e9513a33d9dc12cd5f5f1\">\n.avia-image-container.av-k1sb813u-a682d41e5e0e9513a33d9dc12cd5f5f1 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k1sb813u-a682d41e5e0e9513a33d9dc12cd5f5f1 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k1sb813u-a682d41e5e0e9513a33d9dc12cd5f5f1 av-styling- av-img-linked avia-align-center  avia-builder-el-8  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"http:\/\/ffbenefits.ffga.cm\/allenisd\/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRXCard-2.png\" class='avia_image '  target=\"_blank\"  rel=\"noopener noreferrer\" aria-label='CleverRXCard-2'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2491 avia-img-lazy-loading-not-2491 avia_image ' src=\"\/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRXCard-2.png\" alt='' title='CleverRXCard-2'  height=\"308\" width=\"1006\"  itemprop=\"thumbnailUrl\" srcset=\"\/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRXCard-2.png 1006w, \/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRXCard-2-300x92.png 300w, \/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRXCard-2-768x235.png 768w, \/wp-content\/uploads\/sites\/1667\/2019\/10\/CleverRXCard-2-705x216.png 705w\" sizes=\"(max-width: 1006px) 100vw, 1006px\" \/><\/a><\/div><\/div><\/div><\/div><div  class='hr av-2kv0cz-ad3429ec249744a1b40e666ed6451c01 hr-default  avia-builder-el-9  el_after_av_one_full  el_before_av_one_half '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4w9na1-b059fce7fc2b00c88d19070a0e0ee840\">\n.flex_column.av-4w9na1-b059fce7fc2b00c88d19070a0e0ee840{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-4w9na1-b059fce7fc2b00c88d19070a0e0ee840 av_one_half  avia-builder-el-10  el_after_av_hr  el_before_av_one_half  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1sazsyh-f088c2e73bc4f21de08fae4b06188b5e\">\n.avia-image-container.av-k1sazsyh-f088c2e73bc4f21de08fae4b06188b5e img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k1sazsyh-f088c2e73bc4f21de08fae4b06188b5e .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k1sazsyh-f088c2e73bc4f21de08fae4b06188b5e av-styling- av-img-linked avia-align-center  avia-builder-el-11  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.ventures317.cleverrx&amp;hl=en_US\" class='avia_image '  target=\"_blank\"  rel=\"noopener noreferrer\" aria-label='google-play-badge-300x89'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2494 avia-img-lazy-loading-not-2494 avia_image ' src=\"\/wp-content\/uploads\/sites\/1667\/2019\/10\/google-play-badge-300x89-300x89.png\" alt='' title='google-play-badge-300x89'  height=\"89\" width=\"300\"  itemprop=\"thumbnailUrl\"  \/><\/a><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7rbxl-4106986671c4e3c622d944c4e81b7678\">\n.flex_column.av-7rbxl-4106986671c4e3c622d944c4e81b7678{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-7rbxl-4106986671c4e3c622d944c4e81b7678 av_one_half  avia-builder-el-12  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k1sb0axn-60d1dedbd0dd66377d32cdfc86306d2d\">\n.avia-image-container.av-k1sb0axn-60d1dedbd0dd66377d32cdfc86306d2d img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k1sb0axn-60d1dedbd0dd66377d32cdfc86306d2d .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k1sb0axn-60d1dedbd0dd66377d32cdfc86306d2d av-styling- av-img-linked avia-align-center  avia-builder-el-13  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/apps.apple.com\/us\/app\/clever-rx\/id1443448353\" class='avia_image '  target=\"_blank\"  rel=\"noopener noreferrer\" aria-label='app-store-badge-300x100'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2493 avia-img-lazy-loading-not-2493 avia_image ' src=\"\/wp-content\/uploads\/sites\/1667\/2019\/10\/app-store-badge-300x100-300x100.png\" alt='' title='app-store-badge-300x100'  height=\"100\" width=\"300\"  itemprop=\"thumbnailUrl\"  \/><\/a><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3184","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ffbenefits.ffga.com\/allenisd\/wp-json\/wp\/v2\/pages\/3184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffbenefits.ffga.com\/allenisd\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ffbenefits.ffga.com\/allenisd\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/allenisd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/allenisd\/wp-json\/wp\/v2\/comments?post=3184"}],"version-history":[{"count":0,"href":"https:\/\/ffbenefits.ffga.com\/allenisd\/wp-json\/wp\/v2\/pages\/3184\/revisions"}],"wp:attachment":[{"href":"https:\/\/ffbenefits.ffga.com\/allenisd\/wp-json\/wp\/v2\/media?parent=3184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}