{"id":1576,"date":"2018-05-18T23:05:47","date_gmt":"2018-05-18T23:05:47","guid":{"rendered":"http:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/?page_id=1576"},"modified":"2022-06-20T19:32:22","modified_gmt":"2022-06-20T19:32:22","slug":"accident","status":"publish","type":"page","link":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/accident\/","title":{"rendered":"Accident"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-nbt8a0-c21cca150267ad693ab4ff7317097770\">\n.flex_column.av-nbt8a0-c21cca150267ad693ab4ff7317097770{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-nbt8a0-c21cca150267ad693ab4ff7317097770 av_one_full  avia-builder-el-0  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m6y914-e3ecebad542bdedc41cc45425c58a0db\">\n.avia-image-container.av-m6y914-e3ecebad542bdedc41cc45425c58a0db img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-m6y914-e3ecebad542bdedc41cc45425c58a0db .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-m6y914-e3ecebad542bdedc41cc45425c58a0db av-styling- avia_animated_image av-animated-when-visible-95 right-to-left avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2053 avia-img-lazy-loading-not-2053 avia_image ' src=\"\/wp-content\/uploads\/sites\/2591\/2019\/05\/Accident-1030x139.png\" alt='Accident Insurance' title='Accident'  height=\"139\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"\/wp-content\/uploads\/sites\/2591\/2019\/05\/Accident-1030x139.png 1030w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/Accident-300x41.png 300w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/Accident-768x104.png 768w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/Accident-1500x203.png 1500w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/Accident-705x95.png 705w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/Accident-450x61.png 450w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7x8k8-a4d3be7928e4b4c67902687dee2b9416\">\n.flex_column.av-k7x8k8-a4d3be7928e4b4c67902687dee2b9416{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-k7x8k8-a4d3be7928e4b4c67902687dee2b9416 av_three_fifth  avia-builder-el-2  el_after_av_one_full  el_before_av_two_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-iyd5co-7da8d4945cfe658c7ee9ec398204e30b '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Why Accident Insurance?<\/h3>\n<p>The costs associated with an injury can add up. Between hospital visits, exams and treatment, out-of-pocket costs could put you in a financial hardship. An accident plan pays benefits directly to you so you can determine where to spend the money. It\u2019s comforting to know that an accident insurance policy can be there through all stages of your care, from initial treatment to follow-up care.<\/p>\n<p>Accident coverage is available to you through payroll deduction and may\u00a0provide a benefit for costs associated with:<\/p>\n<ul>\n<li>Concussions<\/li>\n<li>Lacerations<\/li>\n<li>Broken teeth<\/li>\n<li>Emergency room visits<\/li>\n<li>Ambulance, ground or air<\/li>\n<li>Intensive care unit<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-eenl54-e4273db9a4eff7587958417df362c38d\">\n.flex_column.av-eenl54-e4273db9a4eff7587958417df362c38d{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-eenl54-e4273db9a4eff7587958417df362c38d av_two_fifth  avia-builder-el-4  el_after_av_three_fifth  el_before_av_heading  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bx2hqw-6983aadf9986e6b34867a735649b2763\">\n.iconbox.av-bx2hqw-6983aadf9986e6b34867a735649b2763 .iconbox_icon{\nbackground-color:#c42032;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-bx2hqw-6983aadf9986e6b34867a735649b2763  avia-builder-el-5  el_before_av_iconlist  avia-builder-el-first  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: American Fidelity \"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue823' data-av_iconfont='entypo-fontello' title=\"American Fidelity \" desc=\"American Fidelity \" ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/americanfidelity.com' title='American Fidelity '  target=\"_blank\"  rel=\"noopener noreferrer\" >American Fidelity <\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p class=\"p1\">(800) 662-1113<\/p>\n<p><a href=\"https:\/\/americanfidelity.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/americanfidelity.com<\/a><\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803\">\n#top .avia-icon-list-container.av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 .iconlist_icon{\ncolor:#ffffff;\nbackground-color:#c42032;\n}\n#top .avia-icon-list-container.av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 .iconlist_icon svg:first-child{\nstroke:#ffffff;\nfill:#ffffff;\n}\n<\/style>\n<div  class='avia-icon-list-container av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803  avia-builder-el-6  el_after_av_icon_box  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-43bquw-07bcd50ad5f4c797645f764f7a98202c avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue81f' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: ACCIDENT PLAN INFORMATION\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >ACCIDENT PLAN INFORMATION<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p><a href=\"\/wp-content\/uploads\/sites\/2591\/2022\/02\/Accident-Brochure.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Accident Brochure<\/a><\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-6c009205c1c4dd4a4c68139e09b80dd0\">\n#top .av-special-heading.av-av_heading-6c009205c1c4dd4a4c68139e09b80dd0{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-6c009205c1c4dd4a4c68139e09b80dd0 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-6c009205c1c4dd4a4c68139e09b80dd0 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-6c009205c1c4dd4a4c68139e09b80dd0 av-special-heading-h3  avia-builder-el-7  el_after_av_two_fifth  el_before_av_video  av-linked-heading'><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >ACCIDENT INSURANCE VIDEO<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/p>\n<div  class='avia-video av-jv8ozkwj-cfd6c4a74969f2999654428de691320c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/ffga.wistia.com\/medias\/vv4dsar0pe'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Accident Insurance Video\" src=\"https:\/\/fast.wistia.net\/embed\/iframe\/vv4dsar0pe?dnt=1#?secret=Eb4sxB2Zqr\" data-secret=\"Eb4sxB2Zqr\" frameborder=\"0\" scrolling=\"no\" width=\"640\" height=\"360\"><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1576","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/pages\/1576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/comments?post=1576"}],"version-history":[{"count":0,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/pages\/1576\/revisions"}],"wp:attachment":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/media?parent=1576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}