{"id":1580,"date":"2018-05-18T23:16:45","date_gmt":"2018-05-18T23:16:45","guid":{"rendered":"http:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/?page_id=1580"},"modified":"2022-06-20T19:36:03","modified_gmt":"2022-06-20T19:36:03","slug":"critical-illness","status":"publish","type":"page","link":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/critical-illness\/","title":{"rendered":"Critical Illness"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-8ij64-92b65ae59db776b91c609e97f5c2ff54\">\n.flex_column.av-8ij64-92b65ae59db776b91c609e97f5c2ff54{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-8ij64-92b65ae59db776b91c609e97f5c2ff54 av_one_full  avia-builder-el-0  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m5a8jg-0d835087ceb971d5a00b4d5e1d6a9623\">\n.avia-image-container.av-m5a8jg-0d835087ceb971d5a00b4d5e1d6a9623 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-m5a8jg-0d835087ceb971d5a00b4d5e1d6a9623 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-m5a8jg-0d835087ceb971d5a00b4d5e1d6a9623 av-styling- avia_animated_image av-animated-when-visible-95 right-to-left avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2063 avia-img-lazy-loading-not-2063 avia_image ' src=\"\/wp-content\/uploads\/sites\/2591\/2019\/05\/CriticalIllness-1030x139.png\" alt='Critical Illness' title='CriticalIllness'  height=\"139\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"\/wp-content\/uploads\/sites\/2591\/2019\/05\/CriticalIllness-1030x139.png 1030w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/CriticalIllness-300x41.png 300w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/CriticalIllness-768x104.png 768w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/CriticalIllness-1500x203.png 1500w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/CriticalIllness-705x95.png 705w, \/wp-content\/uploads\/sites\/2591\/2019\/05\/CriticalIllness-450x61.png 450w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kx8sx8-03ae7819cb86b6c7640e3c5babe6d3f8\">\n.flex_column.av-kx8sx8-03ae7819cb86b6c7640e3c5babe6d3f8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-kx8sx8-03ae7819cb86b6c7640e3c5babe6d3f8 av_three_fifth  avia-builder-el-2  el_after_av_one_full  el_before_av_two_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-jofai4-9db2fbdda0fdf60530d88ebc241ee103 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3><strong>Why Critical Illness Insurance?<\/strong><\/h3>\n<p>If you\u2019ve heard of heart attacks, strokes, organ transplants or paralysis, then you\u2019re familiar with critical illness. It\u2019s likely you or someone you know has experienced one of these life-altering events. Often times, a critical illness has a powerful impact on people\u2019s lives, affecting their livelihood and finances.<\/p>\n<p>A critical illness plan can help with the treatment costs of covered illnesses. Benefits are paid directly to you, unless otherwise assigned, giving you the choice of how to spend the money. Plus, there are plans available to provide coverage for you, your spouse and dependent children.<\/p>\n<p>Prepare now for the unexpected with a critical illness insurance plan. The plan helps you focus on getting well rather than worrying about finances.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-cb91do-39ece4bf42419dfc3a8b064b63dea3fe\">\n.flex_column.av-cb91do-39ece4bf42419dfc3a8b064b63dea3fe{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-cb91do-39ece4bf42419dfc3a8b064b63dea3fe av_two_fifth  avia-builder-el-4  el_after_av_three_fifth  el_before_av_hr  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bx2hqw-8b6463247763ce7ce9fb1351f3ab66e1\">\n.iconbox.av-bx2hqw-8b6463247763ce7ce9fb1351f3ab66e1 .iconbox_icon{\nbackground-color:#c42032;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-bx2hqw-8b6463247763ce7ce9fb1351f3ab66e1  avia-builder-el-5  el_before_av_iconlist  avia-builder-el-first  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: American Fidelity\"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='' data-av_iconfont='entypo-fontello' title=\"American Fidelity\" desc=\"American Fidelity\" ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='https:\/\/americanfidelity.com' title='American Fidelity'  target=\"_blank\"  rel=\"noopener noreferrer\" >American Fidelity<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p class=\"p1\">(800) 662-1113<\/p>\n<p><a href=\"https:\/\/americanfidelity.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/americanfidelity.com<\/a><\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803\">\n#top .avia-icon-list-container.av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 .iconlist_icon{\ncolor:#ffffff;\nbackground-color:#c42032;\n}\n#top .avia-icon-list-container.av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 .iconlist_icon svg:first-child{\nstroke:#ffffff;\nfill:#ffffff;\n}\n<\/style>\n<div  class='avia-icon-list-container av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803  avia-builder-el-6  el_after_av_icon_box  avia-builder-el-last '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-jv9m4793-2305f16b7ed0c82fc5d61fd2ff230803 avia-iconlist-animate'>\n<li><div class='iconlist_icon av-4qhiak-33a9142fe4291263ab560252005e464c avia-font-entypo-fontello avia-iconfont avia-font-entypo-fontello'><span class='av-icon-char' data-av_icon='\ue81f' data-av_iconfont='entypo-fontello' aria-hidden=\"true\"><\/span><\/div><article class=\"article-icon-entry \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\" aria-label=\"Icon: CRITICAL ILLNESS PLAN INFORMATION\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" >CRITICAL ILLNESS PLAN INFORMATION<\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><p><a href=\"\/wp-content\/uploads\/sites\/2591\/2021\/06\/Critical-Illness-GCI-with-Cancer-Brochure.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Critical Illness (GCI with Cancer) Brochure<\/a><\/p>\n<p><a href=\"\/wp-content\/uploads\/sites\/2591\/2021\/06\/Critical-Illness-GCI-with-CancerRate-Insert.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Critical Illness (GCI with Cancer)(Rate Insert)<\/a><\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/p><\/div><div  class='hr av-hp528s-f0110508a8df7b4bfb69cad031c8a1cc hr-default  avia-builder-el-7  el_after_av_two_fifth  el_before_av_heading '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-076a1a276af5df39b320a00689ba172f\">\n#top .av-special-heading.av-av_heading-076a1a276af5df39b320a00689ba172f{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-076a1a276af5df39b320a00689ba172f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-076a1a276af5df39b320a00689ba172f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-076a1a276af5df39b320a00689ba172f av-special-heading-h3  avia-builder-el-8  el_after_av_hr  el_before_av_video  av-linked-heading'><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >CRITICAL ILLNESS INSURANCE VIDEO<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<div  class='avia-video av-jv8ozkwj-f9104b6e65c97ed7608c0a042d4f8788 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/ffga.wistia.com\/medias\/d9rztrim1s'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Voluntary Critical Illness Video\" src=\"https:\/\/fast.wistia.net\/embed\/iframe\/d9rztrim1s?dnt=1#?secret=nxcKHek7wW\" data-secret=\"nxcKHek7wW\" frameborder=\"0\" scrolling=\"no\" width=\"640\" height=\"360\"><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1580","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/pages\/1580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/comments?post=1580"}],"version-history":[{"count":0,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/pages\/1580\/revisions"}],"wp:attachment":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools-2\/wp-json\/wp\/v2\/media?parent=1580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}