{"id":108,"date":"2018-04-12T16:31:13","date_gmt":"2018-04-12T16:31:13","guid":{"rendered":"http:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/?page_id=108"},"modified":"2022-06-20T19:30:17","modified_gmt":"2022-06-20T19:30:17","slug":"vision","status":"publish","type":"page","link":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/vision\/","title":{"rendered":"Vision"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5gezn0-a87d6b0dc9dec36817b0d2f4fddb53fe\">\n.flex_column.av-5gezn0-a87d6b0dc9dec36817b0d2f4fddb53fe{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5gezn0-a87d6b0dc9dec36817b0d2f4fddb53fe av_one_full  avia-builder-el-0  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-575yfw-36f2ebfac98363283fca2bff3841f53e\">\n.avia-image-container.av-575yfw-36f2ebfac98363283fca2bff3841f53e img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-575yfw-36f2ebfac98363283fca2bff3841f53e .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-575yfw-36f2ebfac98363283fca2bff3841f53e av-styling- avia_animated_image av-animated-when-visible-95 right-to-left avia-align-center  avia-builder-el-1  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2005 avia-img-lazy-loading-not-2005 avia_image ' src=\"\/wp-content\/uploads\/sites\/475\/2019\/05\/Vision-1030x139.png\" alt='' title='Vision'  height=\"139\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"\/wp-content\/uploads\/sites\/475\/2019\/05\/Vision-1030x139.png 1030w, \/wp-content\/uploads\/sites\/475\/2019\/05\/Vision-300x41.png 300w, \/wp-content\/uploads\/sites\/475\/2019\/05\/Vision-768x104.png 768w, \/wp-content\/uploads\/sites\/475\/2019\/05\/Vision-1500x203.png 1500w, \/wp-content\/uploads\/sites\/475\/2019\/05\/Vision-705x95.png 705w, \/wp-content\/uploads\/sites\/475\/2019\/05\/Vision-450x61.png 450w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5042s4-d9497ed7d06f5a723378da25ce82e0e1\">\n.flex_column.av-5042s4-d9497ed7d06f5a723378da25ce82e0e1{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5042s4-d9497ed7d06f5a723378da25ce82e0e1 av_three_fifth  avia-builder-el-2  el_after_av_one_full  el_before_av_two_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><section  class='av_textblock_section av-4w8478-efc4f9285e25b210f676d48415b6b855 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>Why Vision Insurance?<\/h3>\n<p>Proper vision care is essential to your overall wellbeing. Regular eye exams at any age will help prevent eye disease and keep your vision strong for years to come.<\/p>\n<p>Your employer provides you with a vision plan to take care of you and your family\u2019s needs. You must enroll in the vision plan each plan year and premiums are typically paid through payroll deduction. Here are just a few of the areas where you will save money with your plan:<\/p>\n<ul>\n<li>Eye exams<\/li>\n<li>Eyeglasses<\/li>\n<li>Contact lenses<\/li>\n<li>Eye surgeries<\/li>\n<li>Vision correction<\/li>\n<\/ul>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4sjdng-cf09b35b7699125f59aa3766d07cc919\">\n.flex_column.av-4sjdng-cf09b35b7699125f59aa3766d07cc919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-4sjdng-cf09b35b7699125f59aa3766d07cc919 av_two_fifth  avia-builder-el-4  el_after_av_three_fifth  el_before_av_heading  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bx2hqw-0947acd3a8874c1b530c9f56b9b46d6c\">\n.iconbox.av-bx2hqw-0947acd3a8874c1b530c9f56b9b46d6c .iconbox_icon{\nbackground-color:#c42032;\n}\n<\/style>\n<article  class='iconbox iconbox_top av-bx2hqw-0947acd3a8874c1b530c9f56b9b46d6c  avia-builder-el-5  avia-builder-el-no-sibling  main_color'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class=\"iconbox_content\"><header class=\"entry-content-header\" aria-label=\"Icon: ASBAIT\"><div class='iconbox_icon heading-color avia-iconfont avia-font-entypo-fontello' data-av_icon='' data-av_iconfont='entypo-fontello' title=\"ASBAIT\" desc=\"ASBAIT\" ><\/div><h3 class='iconbox_content_title '  itemprop=\"headline\" ><a href='http:\/\/www.asbait.org' title='ASBAIT'  target=\"_blank\"  rel=\"noopener noreferrer\" >ASBAIT<\/a><\/h3><\/header><div class='iconbox_content_container '  itemprop=\"text\" ><p class=\"p1\">(800) 762-2234<\/p>\n<p><a href=\"http:\/\/www.asbait.org\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.asbait.org<\/a><\/p>\n<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-3bfd26620a0d1c03f1225adc792d5091\">\n#top .av-special-heading.av-av_heading-3bfd26620a0d1c03f1225adc792d5091{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-av_heading-3bfd26620a0d1c03f1225adc792d5091 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-3bfd26620a0d1c03f1225adc792d5091 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-3bfd26620a0d1c03f1225adc792d5091 av-special-heading-h3  avia-builder-el-6  el_after_av_two_fifth  el_before_av_video  av-linked-heading'><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >VISION INSURANCE VIDEO<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/p>\n<div  class='avia-video av-jv8ozkwj-fdd3410d6fd2e55e69a508412e6d1f29 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/ffga.wistia.com\/medias\/0vsq03e62x'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Vision Insurance Video\" src=\"https:\/\/fast.wistia.net\/embed\/iframe\/0vsq03e62x?dnt=1#?secret=gcnwji7Vo8\" data-secret=\"gcnwji7Vo8\" frameborder=\"0\" scrolling=\"no\" width=\"640\" height=\"360\"><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-108","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/wp-json\/wp\/v2\/pages\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/wp-json\/wp\/v2\/comments?post=108"}],"version-history":[{"count":0,"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/wp-json\/wp\/v2\/pages\/108\/revisions"}],"wp:attachment":[{"href":"https:\/\/ffbenefits.ffga.com\/bensonunifiedschools\/wp-json\/wp\/v2\/media?parent=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}